{"id":1566,"date":"2024-03-15T04:47:57","date_gmt":"2024-11-18T08:28:39","guid":{"rendered":"https:\/\/dreamy.tours\/?p=5845"},"modified":"2021-10-29T10:57:39","modified_gmt":"2021-10-29T15:57:39","slug":"cachora-no-peru","status":"publish","type":"post","link":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/","title":{"rendered":"CACHORA NO PERU"},"content":{"rendered":"\n<p><strong>Cachora, no Peru,<\/strong> est\u00e1 localizada no departamento de Apurimac, bem na fronteira da estrada entre Abancay e Cusco. \u00c9 o ponto de partida mais popular para os viajantes que querem ver o incr\u00edvel lugar Inca recentemente redescoberto de Choquequirao.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Localizacao_e_geografia\" >Localiza\u00e7\u00e3o\ne geografia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Semana_do_Turismo\" >Semana\ndo Turismo<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Outros_festivais_em_San_Pedro_de_Cachora_incluem\" >Outros festivais em San Pedro de Cachora incluem:<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Turismo_em_San_Pedro_de_Cachora\" >Turismo\nem San Pedro de Cachora<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Turismo_no_Complexo_Arqueologico_Saywite_Arqueologia\" >Turismo\nno Complexo Arqueol\u00f3gico Saywite (Arqueologia)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Turismo_no_Complexo_Arqueologico_de_Sondor_Arqueologia\" >Turismo\nno Complexo Arqueol\u00f3gico de Sondor (Arqueologia)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Turismo_no_Complexo_Arqueologico_de_Curamba_Arqueologia\" >Turismo no Complexo Arqueol\u00f3gico de Curamba\n(Arqueologia)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Turismo_em_Fontes_Quentes_de_Ccocho_Natureza\" >Turismo em Fontes Quentes de Ccocho (Natureza)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Turismo_nas_Fontes_Termais_de_Kilkata_Natureza\" >Turismo nas Fontes Termais de Kilkata  (Natureza)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Turismo_em_Santo_Tomas_Fontes_Quentes_Natureza\" >Turismo em Santo Tom\u00e1s Fontes Quentes (Natureza)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Turismo_nas_Termas_de_Cconoc_Natureza\" >Turismo nas Termas de Cconoc (Natureza)<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Cachora_para_Choquequirao_Trek\" >Cachora para Choquequirao Trek<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#Cachora_para_Machu_Picchu_Trek\" >Cachora\npara Machu Picchu Trek<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-localiza-o-e-geografia\"><span class=\"ez-toc-section\" id=\"Localizacao_e_geografia\"><\/span><strong>Localiza\u00e7\u00e3o\ne geografia<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Est\u00e1\nlocalizada nas seguintes coordenadas geogr\u00e1ficas: 13o31&#8217;06 &#8220;latitude sul e\n72o49&#8217;00&#8221; de longitude oeste, a 2.903 metros acima do n\u00edvel do mar, com\numa \u00e1rea de 108,77 km2 e uma popula\u00e7\u00e3o de 3.849 habitantes, estimada em 2017.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-semana-do-turismo\"><span class=\"ez-toc-section\" id=\"Semana_do_Turismo\"><\/span><strong>Semana\ndo Turismo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O turismo\nem <strong>Cachora, no Peru<\/strong>, embora tenha uma data comovente no calend\u00e1rio, \u00e9\ngeralmente celebrado no final de julho e in\u00edcio de agosto, com as jurisdi\u00e7\u00f5es\nde Abancay, Andahuaylas e Aymaraes como os principais locais.<\/p>\n\n\n\n<p>Entre os\neventos esportivos programados para esta semana est\u00e3o competi\u00e7\u00f5es de canoagem\nnos rios Pampas, Pachachachaca e Apurimac, assim como campeonatos de luta de\ngalos, esportes a\u00e9reos extremos como parapente e esportes terrestres como\nciclismo de montanha.<\/p>\n\n\n\n<p>Al\u00e9m dos programas\nesportivos da Apurimac, planos de turismo est\u00e3o sendo realizados para promover\nas \u00e1reas protegidas na \u00e1rea.<\/p>\n\n\n\n<p>Como n\u00e3o\npode faltar, aqueles que visitarem Apurimac durante a celebra\u00e7\u00e3o de sua Semana,\npoder\u00e3o desfrutar das monumentais feiras gastron\u00f4micas. Junto com as feiras\ngastron\u00f4micas, h\u00e1 tamb\u00e9m feiras de dan\u00e7a, onde as qualidades de dan\u00e7a da\npopula\u00e7\u00e3o s\u00e3o exibidas. Voc\u00ea tamb\u00e9m pode ir \u00e0s interessantes feiras de\nartesanato e agricultura com produtos das terras de Apurimac.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-outros-festivais-em-san-pedro-de-cachora-incluem\"><span class=\"ez-toc-section\" id=\"Outros_festivais_em_San_Pedro_de_Cachora_incluem\"><\/span><strong>Outros festivais em San Pedro de Cachora incluem:<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Festival\nde San Juan<\/li><li>Dia\nde S\u00e3o Pedro<\/li><li>Festa\ndo Senhor de Huanca<\/li><li>Festa\nde S\u00e3o Pedro e Cachora &#8211; Apurimac<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-turismo-em-san-pedro-de-cachora\"><span class=\"ez-toc-section\" id=\"Turismo_em_San_Pedro_de_Cachora\"><\/span><strong>Turismo\nem San Pedro de Cachora<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A cidade de Cachora, no Peru, \u00e9 o in\u00edcio do percurso de cerca de 31,5 km at\u00e9 o complexo arqueol\u00f3gico de Choquequirao, que pode ent\u00e3o ser continuado por cerca de 100 km at\u00e9 o <a href=\"https:\/\/dreamy.tours\/pt-br\/machu-picchu\/\">Santu\u00e1rio Nacional de Machu Picchu<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-turismo-no-complexo-arqueol-gico-saywite-arqueologia\"><span class=\"ez-toc-section\" id=\"Turismo_no_Complexo_Arqueologico_Saywite_Arqueologia\"><\/span><strong>Turismo\nno Complexo Arqueol\u00f3gico Saywite (Arqueologia)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O s\u00edtio\narqueol\u00f3gico de Saywite est\u00e1 localizado no distrito de Curahuasi, dentro da\nprov\u00edncia de Abancay, no departamento de Apurimac, a cerca de 3.500 metros acima\ndo n\u00edvel do mar. \u00c9 um complexo arqueol\u00f3gico que pertenceu \u00e0 cultura inca e foi\nconstru\u00eddo durante o s\u00e9culo XVI. O complexo Saywite ocupa uma \u00e1rea de aproximadamente\n2 hectares onde est\u00e3o alojados importantes amostras de arte l\u00edtica inca,\njuntamente com espa\u00e7os destinados a fins rituais.<\/p>\n\n\n\n<p>O que chama\na aten\u00e7\u00e3o do viajante para visitar Saywite \u00e9 o chamado Saywite Monolith,\nlocalizado no primeiro setor, onde voc\u00ea pode ver uma esp\u00e9cie de modelo de como\nseria o mundo inca. O Saywite Monolith \u00e9 feito de granito e tem aproximadamente\ndois metros de altura e um di\u00e2metro m\u00e9dio de quatro metros, com a maior\ncircunfer\u00eancia de 11,14 metros.<\/p>\n\n\n\n<p>Para que o\nvisitante possa chegar ao S\u00edtio Arqueol\u00f3gico Saywite, deve partir de Abancay e\npercorrer uma dist\u00e2ncia de 47 quil\u00f4metros, em um desvio em quil\u00f4metros para\nchegar a Curahuasi e de l\u00e1 mais 47 km do desvio rodovi\u00e1rio Abancay-Cuzo no km 49.<\/p>\n\n\n\n<p>A entrada\nno Complexo Arqueol\u00f3gico \u00e9 permitida ap\u00f3s o pagamento da passagem que custa s\/\n11,00 para adultos e s\/3,00 para crian\u00e7as e estudantes. A entrada no local \u00e9 de\nsegunda a domingo, das 8h \u00e0s 17h.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-turismo-no-complexo-arqueol-gico-de-sondor-arqueologia\"><span class=\"ez-toc-section\" id=\"Turismo_no_Complexo_Arqueologico_de_Sondor_Arqueologia\"><\/span><strong>Turismo\nno Complexo Arqueol\u00f3gico de Sondor (Arqueologia)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O complexo\narqueol\u00f3gico de Sondor est\u00e1 localizado no distrito de Pacucha, dentro da\nprov\u00edncia de Andahuaylas em Apurimac. Sondor est\u00e1 localizado a uma altura\naproximada de 3.200 metros acima do n\u00edvel do mar, ocupa uma m\u00e9dia de 10\nhectares e teria sido constru\u00eddo com o prop\u00f3sito de ser um Centro Religioso,\nembora existam novas e diferentes teorias sobre sua funcionalidade.<\/p>\n\n\n\n<p>O edif\u00edcio mais\nnot\u00e1vel em Sondor chama-se Muyu Muyu, \u00e9 um promont\u00f3rio, onde voc\u00ea pode ver uma\nconstru\u00e7\u00e3o piramidal de v\u00e1rias plataformas (um total de 8), e onde voc\u00ea pode ver\numa m\u00e9dia de 500 degraus que permitem que as pessoas alcancem a entrada para o\ntopo do edif\u00edcio. Alguns estudiosos acreditam que o Muyu Muyu teria sido usado\nem seu tempo para sacrif\u00edcios humanos e essas ofertas teriam sido feitas no\ntopo da pir\u00e2mide, onde foi encontrado um huaca.<\/p>\n\n\n\n<p>O Sondor\nRaymi, \u00e9 uma atividade que ocorre durante o m\u00eas de junho no Muyu Muyu, \u00e9 uma\nrepresenta\u00e7\u00e3o onde voc\u00ea pode ver a batalha entre os her\u00f3is do grupo Chanka, a\nfim de obter a lideran\u00e7a absoluta do povo. A representa\u00e7\u00e3o come\u00e7a na lagoa\npacucha e termina no Muyu Muyu, onde s\u00e3o observados os sacrif\u00edcios de animais e\no v\u00f4o dos condores.<\/p>\n\n\n\n<p>A entrada\npara o Complexo \u00e9 de segunda a domingo das 8 da manh\u00e3 \u00e0s 5 da tarde e o pre\u00e7o\nda entrada tem um custo de 10,00 S\/ 00 para adultos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-turismo-no-complexo-arqueol-gico-de-curamba-arqueologia\"><span class=\"ez-toc-section\" id=\"Turismo_no_Complexo_Arqueologico_de_Curamba_Arqueologia\"><\/span><strong>Turismo no Complexo Arqueol\u00f3gico de Curamba\n(Arqueologia)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O Complexo\nArqueol\u00f3gico de Curamba, tamb\u00e9m chamado Inca Monte, est\u00e1 localizado no distrito\nde Kishuara, na prov\u00edncia de Andahuaylas, dentro do departamento de Apurimac, a\ncerca de 4.500 metros acima do n\u00edvel do mar. O local foi descoberto pelo\narque\u00f3logo peruano Ra\u00fal del Mar em 1989 e, segundo ele e os cronistas da\nCol\u00f4nia, teria sido um centro metal\u00fargico para o tratamento da prata, o maior\nde seu tipo, que fazia parte da cultura inca. A localiza\u00e7\u00e3o deste Centro\nMetal\u00fargico tamb\u00e9m teria respondido aos prop\u00f3sitos do dom\u00ednio Inca, uma vez que\nap\u00f3s a expuls\u00e3o dos Chankas da \u00e1rea, ele tamb\u00e9m teria funcionado como um Centro\nIntermedi\u00e1rio de Controle Administrativo.<\/p>\n\n\n\n<p>Dentro\ndeste complexo arqueol\u00f3gico, destacam-se: a chamada Montanha Inca junto com a\nchamada Pir\u00e2mide Curamba, tamb\u00e9m conhecida pelos pesquisadores como Ushnu. A\nMontanha Inca \u00e9 um espa\u00e7o onde podem ser encontrados os chamados fornos\nmetal\u00fargicos ou fornos e\u00f3licos, tamb\u00e9m conhecidos como huayras. Os fornos de\nCuramba eram baseados em carv\u00e3o vegetal e acredita-se que o milho tamb\u00e9m era utilizado\ncomo combust\u00edvel, devido aos restos deste encontrado nas cavidades do huayra.<\/p>\n\n\n\n<p>A pir\u00e2mide\nde Curamba, tamb\u00e9m chamada Ushnu, \u00e9 outra atra\u00e7\u00e3o importante do Complexo. Este\nedif\u00edcio quadrangular \u00e9 composto por dois andares ou plataformas, mais uma estrutura\nsubterr\u00e2nea na forma de uma cela ou caverna, e um p\u00e1tio no qual existem v\u00e1rias\nsalas. Acredita-se que uma vez foi usado para fins rituais, especialmente para\nsacrif\u00edcios. Perto desta pir\u00e2mide, a presen\u00e7a de enterro tamb\u00e9m foi encontrada\nnas colinas vizinhas, das quais, de acordo com as cr\u00f4nicas, foram obtidos\nv\u00e1rios restos mortais humanos mumificados.<\/p>\n\n\n\n<p>A entrada\ndo recinto \u00e9 semi-restrita e para acess\u00e1-lo \u00e9 necess\u00e1rio ter a autoriza\u00e7\u00e3o da\nPrefeitura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-turismo-em-fontes-quentes-de-ccocho-natureza\"><span class=\"ez-toc-section\" id=\"Turismo_em_Fontes_Quentes_de_Ccocho_Natureza\"><\/span><strong>Turismo em Fontes Quentes de Ccocho (Natureza)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>No distrito\nde Antabamba, na prov\u00edncia de mesmo nome em Apurimac, voc\u00ea pode encontrar o\nCcocho Hot Springs, um recurso tur\u00edstico ideal para aqueles que t\u00eam uma\npropens\u00e3o para o turismo termo-medicinal. O nome desta atra\u00e7\u00e3o vem do Rio\nCcocho, que o circunda.<\/p>\n\n\n\n<p>A piscina \u00e9\nalimentada pela \u00e1gua de uma fonte cuja temperatura \u00e9 de cerca de 41oC. Os\nminerais que alimentam as \u00e1guas de Ccocho, tornam as fontes termais\nespecialmente recomendadas para pessoas que sofrem de doen\u00e7as reum\u00e1ticas. A\nentrada para as fontes termais \u00e9 livre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-turismo-nas-fontes-termais-de-kilkata-natureza\"><span class=\"ez-toc-section\" id=\"Turismo_nas_Fontes_Termais_de_Kilkata_Natureza\"><\/span><strong>Turismo nas Fontes Termais de Kilkata  (Natureza)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>As fontes\ntermais de Kilkata ou Kilcata s\u00e3o um recurso m\u00e9dico t\u00e9rmico, localizado no\ndistrito de Oropesa, na prov\u00edncia de Antabamba, na regi\u00e3o de Apurimac.<\/p>\n\n\n\n<p>Estas\nfontes quentes t\u00eam uma temperatura superior a 70oC, que \u00e9 quente apesar de suas\n\u00e1guas. Perto do complexo, existem algumas piscinas de lama natural, que junto\ncom as \u00e1guas termais, s\u00e3o recomendadas para pacientes que sofrem de doen\u00e7as\nrelacionadas a problemas \u00f3sseos.<\/p>\n\n\n\n<p>A entrada\nno resort \u00e9 gratuita, e as visitas podem ser feitas at\u00e9 as 16h00. Existem\napenas duas maneiras de chegar \u00e0s fontes termais de Kilkata: a p\u00e9 e a p\u00e9, por\nisso \u00e9 aconselh\u00e1vel antecipar este inconveniente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-turismo-em-santo-tom-s-fontes-quentes-natureza\"><span class=\"ez-toc-section\" id=\"Turismo_em_Santo_Tomas_Fontes_Quentes_Natureza\"><\/span><strong>Turismo em Santo Tom\u00e1s Fontes Quentes (Natureza)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>No distrito\nde Pichirhua, na prov\u00edncia de Abancay, na regi\u00e3o de Apurimac, est\u00e3o as \u00e1guas\ntermais de Santo Tom\u00e1s.<\/p>\n\n\n\n<p>Essas\nfontes termais est\u00e3o localizadas nas margens do rio Pachachaca e surgem de duas\nfontes de \u00e1gua distribu\u00eddas em piscinas rudimentares no territ\u00f3rio circundante.\nOs minerais que nutrem as \u00e1guas das nascentes de Santo Tom\u00e1s s\u00e3o recomendados\npara pessoas com doen\u00e7as musculares ou altos n\u00edveis de estresse, j\u00e1 que possuem\npropriedades relaxantes e analg\u00e9sicas.<\/p>\n\n\n\n<p>Para chegar\n\u00e0s termas de Santo Tom\u00e1s, \u00e9 necess\u00e1rio fazer uma caminhada ao longo de uma\ntrilha de 5 km. A entrada nas fontes termais \u00e9 livre e, embora o lugar possa\nser visitado a qualquer momento, \u00e9 prefer\u00edvel faz\u00ea-lo pela manh\u00e3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-turismo-nas-termas-de-cconoc-natureza\"><span class=\"ez-toc-section\" id=\"Turismo_nas_Termas_de_Cconoc_Natureza\"><\/span><strong>Turismo nas Termas de Cconoc (Natureza)<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Nas margens\ndo rio Apurimac, existem as nascentes termais de Cconoc. Estas termas est\u00e3o\nlocalizadas no distrito de Curahuasi, na prov\u00edncia de Abancay, na regi\u00e3o de\nApurimac.<\/p>\n\n\n\n<p>Sabe-se que\nos minerais que alimentam as termas de Cconoc fazem com que as \u00e1guas destes\nbanhos sejam especialmente recomendadas para pacientes com doen\u00e7as \u00f3sseas ou\nmusculares. Os banhos Cconoc s\u00e3o alcan\u00e7ados ap\u00f3s uma viagem de duas horas a\npartir da cidade de Abancay.<\/p>\n\n\n\n<p>A entrada\npara os banhos Cconoc \u00e9 permitida, ap\u00f3s a apresenta\u00e7\u00e3o de um bilhete, cujo\ncusto \u00e9 de 2,00 s \/ 2,00 para adultos. Gra\u00e7as \u00e0 popularidade do local, possui\numa infra-estrutura tur\u00edstica b\u00e1sica, bem como acomoda\u00e7\u00f5es modestas e servi\u00e7o\nde alimenta\u00e7\u00e3o mediante solicita\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cachora-para-choquequirao-trek\"><span class=\"ez-toc-section\" id=\"Cachora_para_Choquequirao_Trek\"><\/span><strong>Cachora para Choquequirao Trek<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A maneira mais comum de ir de <strong>Cachora a Choquequirao<\/strong> \u00e9 atrav\u00e9s do tour Choquequirao de 4 dias e 3 noites. Voc\u00ea pode contratar este tour online ou diretamente em uma ag\u00eancia na cidade de Cusco.<\/p>\n\n\n\n<p>O passeio\nde <strong>Cachora a Choquequirao<\/strong> em 4 dias e 3 noites \u00e9 assim<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Dia 1<\/strong>: O\npasseio de <strong>Cachora a Choquequirao<\/strong> come\u00e7a na cidade de Cusco entre 5 a.m.\nou 6 a.m. Nesse momento, o \u00f4nibus parte para Cachora (4 ou 5 horas de viagem).\nL\u00e1 voc\u00ea descansa um pouco para iniciar a rota de trekking. Ap\u00f3s cerca de 5\nhoras de caminhada, voc\u00ea passa a noite nas margens do rio Apurimac.<\/li><li><strong>Dia 2<\/strong>: A\ncaminhada continua muito cedo ap\u00f3s o caf\u00e9 da manh\u00e3. A subida torna-se mais\n\u00e1rdua at\u00e9 chegar a Marampata (3.000 m.a.s.l.). O percurso continua at\u00e9\nfinalmente chegar ao s\u00edtio arqueol\u00f3gico de Choquequirao, ap\u00f3s 10 quil\u00f4metros de\nestrada.<\/li><li><strong>Dia 3<\/strong>: Depois\nde apreciar as \u00e1reas mais remotas de Choquequirao, a viagem de retorno come\u00e7a\nda mesma maneira que voc\u00ea chegou. Depois de quase 5 horas de caminhada, um\nacampamento \u00e9 estabelecido na \u00e1rea de Chiquisca.<\/li><li><strong>Dia 4<\/strong>: O \u00faltimo\ndia come\u00e7a cedo. Na rota, voc\u00ea chegar\u00e1 ao mirante Wayna Qali, onde poder\u00e1\napreciar a beleza do Canyon Apurimac (considerado o mais belo da Am\u00e9rica do\nSul). Ap\u00f3s aproximadamente 3 horas de caminhada, voc\u00ea chegar\u00e1 \u00e0 cidade de\nCachora, onde um carro retornar\u00e1 o turista \u00e0 cidade de Cusco.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cachora-para-machu-picchu-trek\"><span class=\"ez-toc-section\" id=\"Cachora_para_Machu_Picchu_Trek\"><\/span><strong>Cachora\npara Machu Picchu Trek<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>H\u00e1 outro\npasseio que liga <strong>Cachora com Machu Picchu<\/strong> em 8 dias e 7 noites. No\ntotal, 115 quil\u00f4metros de hist\u00f3ria e aventura s\u00e3o cobertos.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Dia 1:<\/strong> A\naventura <strong>Cachora a Machu Picchu<\/strong> nesse dia come\u00e7a em Cusco e termina \u00e0s\nmargens do rio Apurimac ap\u00f3s uma viagem de \u00f4nibus at\u00e9 a cidade de Cachora. Voc\u00ea\ncaminha cerca de 4 ou 5 horas naquele dia.<\/li><li><strong>Dia 2<\/strong>: O dia\ncome\u00e7a cedo com uma subida dif\u00edcil (4 ou 5 horas no caminho) at\u00e9 chegar ao\ns\u00edtio arqueol\u00f3gico de Choquequirao.<\/li><li><strong>Dia 3<\/strong>:\nDepois de percorrer Choquequirao, a rota de <strong>Cachora a Machu Picchu<\/strong>\ncontinua por lugares como o setor Rio Blanco e o setor Maizal. O dia \u00e9\nexigente, mas gratificante, devido \u00e0s paisagens que atravessa.<\/li><li><strong>Dia 4:<\/strong> A\nviagem atravessa o Passo Yanama, e depois chega \u00e0 chamada &#8220;Mina\nVictoria&#8221;, um antigo dep\u00f3sito de prata. O dia n\u00e3o \u00e9 t\u00e3o exigente quanto o\nanterior.<\/li><li><strong>Dia 5<\/strong>: Este\ndia come\u00e7a a descida para a geografia tropical do Peru. Voc\u00ea pode ver a \u00e1rea de\n&#8216;Totora&#8217; e o acampamento &#8216;Collpa&#8217;. O dia n\u00e3o \u00e9 exigente.<\/li><li><strong>Dia 6<\/strong>: O dia\npassa por belas paisagens como v\u00e1rias planta\u00e7\u00f5es de banana e caf\u00e9. A descida\nchega a &#8216;La Playa&#8217;, onde cai uma queda d&#8217;\u00e1gua.<\/li><li><strong>Dia 7<\/strong>: O dia\ncome\u00e7a muito cedo at\u00e9 chegarmos \u00e0 chamada &#8220;Usina Hidrel\u00e9trica&#8221;. O\npasseio continua at\u00e9 a cidade de \u00c1guas Calientes, aos p\u00e9s de Machu Picchu. L\u00e1\nvoc\u00ea passar\u00e1 a noite em um hotel ou alojamento.<\/li><li><strong>Dia 8<\/strong>: O dia\ncome\u00e7a com uma escalada a Machu Picchu. Essa manh\u00e3, e parte da tarde, \u00e9\ndedicada a um passeio pela Maravilha do Mundo. Ent\u00e3o, o retorno a Cusco \u00e9 de\ntrem e \u00f4nibus.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Cachora, no Peru, est\u00e1 localizada no departamento de Apurimac, bem na fronteira da estrada entre Abancay e Cusco. \u00c9 o ponto de partida mais popular &#8230;<\/p>\n","protected":false},"author":1,"featured_media":909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-1566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cusco-dicas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CACHORA NO PERU - Dreamy Tours<\/title>\n<meta name=\"description\" content=\"Cachora, no Peru, est\u00e1 localizada no departamento de Apurimac, \u00e9 o ponto de partida mais popular para os viajantes que querem ver o incr\u00edvel lugar Inca.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CACHORA NO PERU\" \/>\n<meta property=\"og:description\" content=\"Cachora, no Peru, est\u00e1 localizada no departamento de Apurimac, \u00e9 o ponto de partida mais popular para os viajantes que querem ver o incr\u00edvel lugar Inca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/\" \/>\n<meta property=\"og:site_name\" content=\"Dreamy Tours\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dreamytours\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-18T08:28:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/2-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dreamy Tours\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Dreamy_tours\" \/>\n<meta name=\"twitter:site\" content=\"@Dreamy_tours\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dreamy Tours\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/\"},\"author\":{\"name\":\"Dreamy Tours\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#\\\/schema\\\/person\\\/26a2534daf9eaf4cd6da8db3941552d5\"},\"headline\":\"CACHORA NO PERU\",\"datePublished\":\"2024-11-18T08:28:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/\"},\"wordCount\":2143,\"publisher\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/2-8.jpg\",\"articleSection\":[\"Cusco dicas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/\",\"name\":\"CACHORA NO PERU - Dreamy Tours\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/2-8.jpg\",\"datePublished\":\"2024-11-18T08:28:39+00:00\",\"description\":\"Cachora, no Peru, est\u00e1 localizada no departamento de Apurimac, \u00e9 o ponto de partida mais popular para os viajantes que querem ver o incr\u00edvel lugar Inca.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/2-8.jpg\",\"contentUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/2-8.jpg\",\"width\":1200,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/cachora-no-peru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CACHORA NO PERU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/\",\"name\":\"Dreamy Tours\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#organization\",\"name\":\"Dreamy Tours\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/dreamy-tour-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/dreamy-tour-cuadrado.jpg\",\"width\":696,\"height\":696,\"caption\":\"Dreamy Tours\"},\"image\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dreamytours\",\"https:\\\/\\\/x.com\\\/Dreamy_tours\",\"https:\\\/\\\/www.instagram.com\\\/dreamy_tours\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/dreamy_tours\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGKP_C9x8GBYl7l8D0QD9Fg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#\\\/schema\\\/person\\\/26a2534daf9eaf4cd6da8db3941552d5\",\"name\":\"Dreamy Tours\",\"sameAs\":[\"https:\\\/\\\/dreamy.tours\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CACHORA NO PERU - Dreamy Tours","description":"Cachora, no Peru, est\u00e1 localizada no departamento de Apurimac, \u00e9 o ponto de partida mais popular para os viajantes que querem ver o incr\u00edvel lugar Inca.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/","og_locale":"pt_BR","og_type":"article","og_title":"CACHORA NO PERU","og_description":"Cachora, no Peru, est\u00e1 localizada no departamento de Apurimac, \u00e9 o ponto de partida mais popular para os viajantes que querem ver o incr\u00edvel lugar Inca.","og_url":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/","og_site_name":"Dreamy Tours","article_publisher":"https:\/\/www.facebook.com\/dreamytours","article_published_time":"2024-11-18T08:28:39+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/2-8.jpg","type":"image\/jpeg"}],"author":"Dreamy Tours","twitter_card":"summary_large_image","twitter_creator":"@Dreamy_tours","twitter_site":"@Dreamy_tours","twitter_misc":{"Escrito por":"Dreamy Tours","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#article","isPartOf":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/"},"author":{"name":"Dreamy Tours","@id":"https:\/\/dreamy.tours\/pt-br\/#\/schema\/person\/26a2534daf9eaf4cd6da8db3941552d5"},"headline":"CACHORA NO PERU","datePublished":"2024-11-18T08:28:39+00:00","mainEntityOfPage":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/"},"wordCount":2143,"publisher":{"@id":"https:\/\/dreamy.tours\/pt-br\/#organization"},"image":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/2-8.jpg","articleSection":["Cusco dicas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/","url":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/","name":"CACHORA NO PERU - Dreamy Tours","isPartOf":{"@id":"https:\/\/dreamy.tours\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#primaryimage"},"image":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/2-8.jpg","datePublished":"2024-11-18T08:28:39+00:00","description":"Cachora, no Peru, est\u00e1 localizada no departamento de Apurimac, \u00e9 o ponto de partida mais popular para os viajantes que querem ver o incr\u00edvel lugar Inca.","breadcrumb":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#primaryimage","url":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/2-8.jpg","contentUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/2-8.jpg","width":1200,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/dreamy.tours\/pt-br\/blog\/cachora-no-peru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dreamy.tours\/pt-br\/"},{"@type":"ListItem","position":2,"name":"CACHORA NO PERU"}]},{"@type":"WebSite","@id":"https:\/\/dreamy.tours\/pt-br\/#website","url":"https:\/\/dreamy.tours\/pt-br\/","name":"Dreamy Tours","description":"","publisher":{"@id":"https:\/\/dreamy.tours\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dreamy.tours\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/dreamy.tours\/pt-br\/#organization","name":"Dreamy Tours","url":"https:\/\/dreamy.tours\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dreamy.tours\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/dreamy.tours\/wp-content\/uploads\/dreamy-tour-cuadrado.jpg","contentUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/dreamy-tour-cuadrado.jpg","width":696,"height":696,"caption":"Dreamy Tours"},"image":{"@id":"https:\/\/dreamy.tours\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dreamytours","https:\/\/x.com\/Dreamy_tours","https:\/\/www.instagram.com\/dreamy_tours\/","https:\/\/www.pinterest.es\/dreamy_tours\/","https:\/\/www.youtube.com\/channel\/UCGKP_C9x8GBYl7l8D0QD9Fg"]},{"@type":"Person","@id":"https:\/\/dreamy.tours\/pt-br\/#\/schema\/person\/26a2534daf9eaf4cd6da8db3941552d5","name":"Dreamy Tours","sameAs":["https:\/\/dreamy.tours"]}]}},"author_meta":{"display_name":"Dreamy Tours","author_link":"https:\/\/dreamy.tours\/pt-br\/blog\/author\/admin_dt\/"},"featured_img":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/2-8.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/dreamy.tours\/pt-br\/blog\/category\/cusco-dicas\/\" class=\"advgb-post-tax-term\">Cusco dicas<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Cusco dicas<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 5 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 15 mar\u00e7o, 2024","modified":"Atualizado em 29 outubro, 2021"},"absolute_dates_time":{"created":"Publicado em 15 mar\u00e7o, 2024 4:47 am","modified":"Atualizado em 29 outubro, 2021 10:57 am"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/posts\/1566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/comments?post=1566"}],"version-history":[{"count":0,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/posts\/1566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/media\/909"}],"wp:attachment":[{"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/media?parent=1566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/categories?post=1566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/tags?post=1566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}