{"id":1486,"date":"2024-03-18T09:48:13","date_gmt":"2024-12-03T20:44:13","guid":{"rendered":"https:\/\/dreamy.tours\/?p=5656"},"modified":"2025-07-08T18:26:21","modified_gmt":"2025-07-08T23:26:21","slug":"a-renascenca-na-america","status":"publish","type":"post","link":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/","title":{"rendered":"RENASCEN\u00c7A NA AM\u00c9RICA"},"content":{"rendered":"\n<p>Na\nRenascen\u00e7a americana, a ornamenta\u00e7\u00e3o renascentista \u00e9 misturada com temas\ninspirados na agenda decorativa dos nativos americanos. Existem dois centros\nprincipais: M\u00e9xico e Peru. Em ambas, as ordens religiosas ser\u00e3o as que\nintroduzir\u00e3o as formas renascentistas e, ao mesmo tempo, criar\u00e3o no M\u00e9xico um\ntipo original de constru\u00e7\u00e3o: a igreja precedida por um enorme \u00e1trio, para\ncatequese, com uma capela aberta, dada a impossibilidade material de todos os\n\u00edndios entrarem na igreja; no \u00e1trio estava a &#8220;posa&#8221;, uma esp\u00e9cie de\nlugar humilde para o ensino. Algumas igrejas t\u00eam uma passarela para sua defesa,\ncomo Tepeaca, com duas passarelas.<\/p>\n\n\n\n<p>Os\nprincipais exemplos destes conventos no M\u00e9xico s\u00e3o os de Teposcolula, com uma\nmagn\u00edfica capela aberta; Cholula, Huejotzingo, San Agust\u00edn Acolm\u00e1n, com uma\nmagn\u00edfica fachada plateresca, que tem seu eco em Yuririap\u00fandaro, e o de\nActop\u00e1n, entre outros. Entre as constru\u00e7\u00f5es civis, o edif\u00edcio mais importante \u00e9\no pal\u00e1cio Hern\u00e1n Cort\u00e9s em Cuernavaca e a magn\u00edfica fachada da casa Montejo em\nM\u00e9rida de Yucat\u00e1n.<\/p>\n\n\n\n<p>Na segunda\nmetade do s\u00e9culo, grandes catedrais foram constru\u00eddas, como a do M\u00e9xico,\nseguindo o modelo da catedral de Puebla. A de Guadalajara foi inspirada no\nmodelo de Granada de Diego de Silo\u00e9 e a de P\u00e9tzcuaro (Michoac\u00e1n) apresentou um\nplano muito original baseado em um pent\u00e1gono. As catedrais de M\u00e9rida e Oaxaca\ntamb\u00e9m s\u00e3o deste per\u00edodo.<\/p>\n\n\n\n<p>No Peru, a\ninflu\u00eancia Mud\u00e9jar \u00e9 evidente nos telhados, devido ao uso de cer\u00e2mica tipo\nMud\u00e9jar, principalmente por causa da freq\u00fc\u00eancia dos terremotos, que destru\u00edram\na maior parte dos edif\u00edcios deste per\u00edodo. As catedrais de Lima e Cuzco s\u00e3o\ncaracter\u00edsticas da segunda metade do s\u00e9culo, na qual interveio Francisco\nBecerra, que havia trabalhado anteriormente em Puebla (M\u00e9xico) e Quito.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#O_ambiente_historico\" >O ambiente hist\u00f3rico<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#Tendencias_culturais\" >Tend\u00eancias culturais<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#Arte_Renascentista_Americana\" >Arte Renascentista Americana<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#Caracteristicas_gerais_da_arte_renascentista_americana\" >Caracter\u00edsticas gerais da arte renascentista\namericana<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#Influencia_da_arte_grega\" >Influ\u00eancia da arte grega<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#Humanismo\" >Humanismo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#Pintura_melhorada\" >Pintura melhorada<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#Renascenca_comercial\" >Renascen\u00e7a comercial<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#O_reencontro_dos_textos_classicos\" >O reencontro dos textos cl\u00e1ssicos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#Influencia_do_cristianismo\" >Influ\u00eancia\ndo cristianismo<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#Arquitetura_Renascentista_Americana\" >Arquitetura Renascentista Americana<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#Fundamentos_gerais_da_Arquitetura_Renascentista_Americana\" >Fundamentos gerais da Arquitetura Renascentista\nAmericana<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#Caracteristicas_gerais_da_Arquitetura_Renascentista_Americana\" >Caracter\u00edsticas gerais da Arquitetura\nRenascentista Americana<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-o-ambiente-hist-rico\"><span class=\"ez-toc-section\" id=\"O_ambiente_historico\"><\/span><strong>O ambiente hist\u00f3rico<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Descoberta,\nexplora\u00e7\u00e3o, conquista e coloniza\u00e7\u00e3o de terras americanas sob o reinado dos Reis\nCat\u00f3licos (1474-1517), Imperador Carlos V (1517-1556) e Filipe II (1556-1598).<\/p>\n\n\n\n<p>Em 1492 os\nReis Cat\u00f3licos puseram fim \u00e0 Reconquista contra os \u00e1rabes, que come\u00e7ou logo\nap\u00f3s a invas\u00e3o \u00e1rabe da Pen\u00ednsula em 711. O potencial espiritual, fruto da\neuforia da unidade recuperada pela Espanha, \u00e9 transferido para a Am\u00e9rica. Com\nCarlos V, a Casa da \u00c1ustria, a dinastia dos Habsburgos, entrou na Espanha\n(Carlos V \u00e9 o filho de Joana a Louca, filha dos Reis Cat\u00f3licos, e Filipe o\nBelo, filho do Imperador Maximiliano I da \u00c1ustria.<\/p>\n\n\n\n<p>Charles V\nquer realizar a id\u00e9ia imperial de uma Europa unificada sob o signo\ncrist\u00e3o-hisp\u00e2nico. Seu filho Felipe II, construtor do mosteiro de El Escorial,\nperto de Madri, tentar\u00e1 fechar os Pieineos para evitar qualquer influ\u00eancia da\nReforma Protestante; com isso inaugura o &#8220;Per\u00edodo Nacional&#8221; no qual a\nEspanha se retira em si mesma e tenta preservar o imp\u00e9rio ultramarino (aquele\nem cujas terras &#8220;o sol n\u00e3o se p\u00f4s&#8221;, nas palavras de Carlos V). O\npoder imperial espanhol est\u00e1 quebrado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-tend-ncias-culturais\"><span class=\"ez-toc-section\" id=\"Tendencias_culturais\"><\/span><strong>Tend\u00eancias culturais<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A primeira\nRenascen\u00e7a. A literatura destes anos \u00e9 geralmente considerada como a primeira\nRenascen\u00e7a e \u00e9 caracterizada pela importa\u00e7\u00e3o de formas e id\u00e9ias da It\u00e1lia.\nConquistadores e mission\u00e1rios os trouxeram para o Novo Mundo. Eles eram at\u00e9\nmesmo escritores dos Estados Unidos.<\/p>\n\n\n\n<p>Os\nprimeiros escritores na Am\u00e9rica seguiram as linhas que dominavam na Espanha.\nHavia escritores Erasmian, mas o que aconteceu na primeira etapa da coloniza\u00e7\u00e3o\noferece um aspecto medieval. Os livros que circulavam eram em sua maioria\neclesi\u00e1sticos e educativos. Mas os g\u00eaneros, com apar\u00eancia medieval, s\u00e3o aqueles\nque adquirem for\u00e7a criativa com o contato com a nova realidade: a cr\u00f4nica, que\nj\u00e1 vimos, e o teatro mission\u00e1rio. As id\u00e9ias que importam s\u00e3o as do humanismo\nErasmic.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-arte-renascentista-americana\"><span class=\"ez-toc-section\" id=\"Arte_Renascentista_Americana\"><\/span><strong>Arte Renascentista Americana<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A <strong>arte\nrenascentista americana<\/strong> \u00e9 um estilo art\u00edstico que inclui pintura, escultura\ne arquitetura que surgiu na Europa por volta de 1400; especificamente na\nIt\u00e1lia. A <strong>arte renascentista americana<\/strong> foi um dos principais expoentes\nda Renascen\u00e7a europ\u00e9ia. Nesta fase, artistas que ainda t\u00eam reputa\u00e7\u00e3o, como\nBoticelli, Giotto e van der Weyden, come\u00e7aram a ser reconhecidos.<\/p>\n\n\n\n<p>O movimento\nfoi baseado principalmente em uma combina\u00e7\u00e3o de aspectos medievais da \u00e9poca e\nid\u00e9ias modernas que come\u00e7aram a surgir no in\u00edcio do s\u00e9culo XV.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-caracter-sticas-gerais-da-arte-renascentista-americana\"><span class=\"ez-toc-section\" id=\"Caracteristicas_gerais_da_arte_renascentista_americana\"><\/span><strong>Caracter\u00edsticas gerais da arte renascentista\namericana<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-influ-ncia-da-arte-grega\"><span class=\"ez-toc-section\" id=\"Influencia_da_arte_grega\"><\/span><strong>Influ\u00eancia da arte grega<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Isto\naconteceu depois que artistas italianos da \u00e9poca estudaram textos, obras e arte\ngregos para us\u00e1-los como inspira\u00e7\u00e3o para suas cria\u00e7\u00f5es. O que influenciou esta\nmudan\u00e7a na percep\u00e7\u00e3o da arte foi Petrarca, um famoso artista italiano do s\u00e9culo\nXIV.<\/p>\n\n\n\n<p>Isto deu\norigem a um movimento n\u00e3o apenas baseado na adapta\u00e7\u00e3o da cultura humana a uma\nera p\u00f3s-medieval, mas tamb\u00e9m aderiu aos princ\u00edpios tradicionais das obras\nantigas que marcaram um antes e um depois na arte.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-humanismo\"><span class=\"ez-toc-section\" id=\"Humanismo\"><\/span><strong>Humanismo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>A maior\nparte da arte produzida na Renascen\u00e7a foi inspirada pela cren\u00e7a filos\u00f3fica no\nhumanismo. Por si s\u00f3, o humanismo j\u00e1 havia desempenhado um papel importante em\nin\u00fameras realiza\u00e7\u00f5es na Gr\u00e9cia antiga, tais como o surgimento de id\u00e9ias\ndemocr\u00e1ticas na pol\u00edtica.<\/p>\n\n\n\n<p>Esta cren\u00e7a\najudou os artistas a deixar de lado a influ\u00eancia religiosa que geralmente era\nencarnada nas obras da \u00e9poca.<\/p>\n\n\n\n<p>O humanismo\ntamb\u00e9m causou mais aten\u00e7\u00e3o aos detalhes das caracter\u00edsticas das pessoas na\npintura.<\/p>\n\n\n\n<p>Os\ntrabalhos da Renascen\u00e7a concentraram-se na cren\u00e7a humanista de que a\u00e7\u00f5es\ncorretas eram a chave para a felicidade, mas a influ\u00eancia religiosa que este\nconceito poderia ter deixado de lado.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-pintura-melhorada\"><span class=\"ez-toc-section\" id=\"Pintura_melhorada\"><\/span><strong>Pintura melhorada<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Durante o\ns\u00e9culo XV, v\u00e1rios pintores holandeses de renome desenvolveram melhorias na\nforma como a pintura a \u00f3leo foi criada. Durante o per\u00edodo renascentista, os\nartistas italianos utilizaram novas t\u00e9cnicas holandesas para melhorar suas\npinturas.<\/p>\n\n\n\n<p>Este\nfen\u00f4meno teve um efeito na qualidade e durabilidade das obras art\u00edsticas e\nprovocou mudan\u00e7as significativas na pintura em escala global.<\/p>\n\n\n\n<p>Al\u00e9m disso,\no Renascimento foi em grande parte devido \u00e0 presen\u00e7a de brilhantes personagens\nitalianos. Muitos deles passaram a ser considerados os melhores de todos os\ntempos em termos de influ\u00eancia, tais como Piero della Francesca e Donatello.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-renascen-a-comercial\"><span class=\"ez-toc-section\" id=\"Renascenca_comercial\"><\/span><strong>Renascen\u00e7a comercial<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>A\nRenascen\u00e7a foi refor\u00e7ada pela nova capacidade das regi\u00f5es de comercializar seus\npr\u00f3prios bens naturais.<\/p>\n\n\n\n<p>Em outras\npalavras, cada regi\u00e3o desenvolveu um sistema comercial de exporta\u00e7\u00e3o que\naumentou significativamente sua riqueza.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-o-reencontro-dos-textos-cl-ssicos\"><span class=\"ez-toc-section\" id=\"O_reencontro_dos_textos_classicos\"><\/span><strong>O reencontro dos textos cl\u00e1ssicos<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Uma das\nprincipais influ\u00eancias da literatura renascentista foi o reaparecimento de\ntextos medievais que haviam sido perdidos na Idade M\u00e9dia da humanidade.<\/p>\n\n\n\n<p>Os\nliter\u00e1rios que estudaram estes textos usaram suas influ\u00eancias para melhorar\nsuas obras e dar um toque antigo ao movimento, que era ent\u00e3o contempor\u00e2neo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-influ-ncia-do-cristianismo\"><span class=\"ez-toc-section\" id=\"Influencia_do_cristianismo\"><\/span><strong>Influ\u00eancia\ndo cristianismo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Embora as\nobras criadas durante o per\u00edodo renascentista n\u00e3o estivessem ligadas \u00e0s\ncr\u00edticas da Igreja Cat\u00f3lica, a religi\u00e3o crist\u00e3 serviu como uma influ\u00eancia\npositiva para v\u00e1rios dos expoentes deste movimento cultural.<\/p>\n\n\n\n<p>Entre eles\nestava Erasmo, o homem liter\u00e1rio holand\u00eas, que usou o cristianismo nos\nprimeiros quatro s\u00e9culos como inspira\u00e7\u00e3o para suas obras.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-arquitetura-renascentista-americana\"><span class=\"ez-toc-section\" id=\"Arquitetura_Renascentista_Americana\"><\/span><strong>Arquitetura Renascentista Americana<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u00c9 aquela\nproduzida durante o per\u00edodo art\u00edstico do Renascimento europeu, que se estendeu\npelos s\u00e9culos XIV, XV e XVI. Caracteriza-se por ser um momento de ruptura na\nHist\u00f3ria da Arquitetura, especialmente em rela\u00e7\u00e3o ao estilo arquitet\u00f4nico\nanterior: o g\u00f3tico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-fundamentos-gerais-da-arquitetura-renascentista-americana\"><span class=\"ez-toc-section\" id=\"Fundamentos_gerais_da_Arquitetura_Renascentista_Americana\"><\/span><strong>Fundamentos gerais da Arquitetura Renascentista\nAmericana<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A Escola de\nAtenas, de Rafael Sanzio, \u00e9 uma obra que serve como exemplo da rela\u00e7\u00e3o entre o\nRenascimento e o Humanismo e o Classicismo. Artigo principal: Renascen\u00e7a<\/p>\n\n\n\n<p>A <strong>Arquitetura\nRenascentista Americana<\/strong> estava intimamente relacionada a uma vis\u00e3o do mundo\ndurante aquele per\u00edodo apoiada por dois pilares essenciais: Classicismo e\nhumanismo.<\/p>\n\n\n\n<p>Deve-se\nnotar que os ideais e valores da <strong>Arquitetura Renascentista americana<\/strong> n\u00e3o\npodiam surgir totalmente alheios \u00e0 heran\u00e7a medieval que a precedeu, no entanto,\nos conceitos subjacentes a este estilo arquitet\u00f4nico foram constru\u00eddos sobre a\nruptura consciente e efetiva da produ\u00e7\u00e3o art\u00edstica da Idade M\u00e9dia, em estilo\ng\u00f3tico especial.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-caracter-sticas-gerais-da-arquitetura-renascentista-americana\"><span class=\"ez-toc-section\" id=\"Caracteristicas_gerais_da_Arquitetura_Renascentista_Americana\"><\/span><strong>Caracter\u00edsticas gerais da Arquitetura\nRenascentista Americana<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Podemos\nanalisar as seguintes caracter\u00edsticas gerais:<\/p>\n\n\n\n<p><strong>Busca do\nideal cl\u00e1ssico:<\/strong>\nAtrav\u00e9s do classicismo, os homens renascentistas olharam para o mundo greco-romano\ncomo um modelo para sua sociedade contempor\u00e2nea, procurando aplicar na\nrealidade material cotidiana o que eles consideravam pertencer a um mundo mais\nid\u00edlico do que real. Neste sentido, a arquitetura, em particular, tentou\nespecificar conceitos cl\u00e1ssicos como beleza, emergindo assim a teoriza\u00e7\u00e3o e a\nordem de movimento, baseada na arquitetura grega e romana cl\u00e1ssica. Segundo os\nte\u00f3ricos da Renascen\u00e7a, este era o caminho ideal para alcan\u00e7ar o mundo ideal.<\/p>\n\n\n\n<p><strong>Vis\u00e3o\nprofana sobre temas religiosos:<\/strong> Os valores cl\u00e1ssicos, do ponto de vista do cristianismo, de enorme\ninflu\u00eancia neste per\u00edodo (levando em conta que o Renascimento surge na It\u00e1lia,\nonde a presen\u00e7a da Igreja Cat\u00f3lica foi decisiva para a Arte), foram\nconsiderados de car\u00e1ter pag\u00e3o e pecaminoso. Para superar esta censura da Igreja\nCat\u00f3lica, a vis\u00e3o do mundo crist\u00e3o foi integrada ao projeto de recupera\u00e7\u00e3o dos\nideais cl\u00e1ssicos, atrav\u00e9s de cenas desacralizadas e edif\u00edcios feitos sob medida\npara o homem. Esta foi outra das inova\u00e7\u00f5es do movimento.<\/p>\n\n\n\n<p><strong>Influ\u00eancia\nda natureza:<\/strong> A\nnatureza era vista como a cria\u00e7\u00e3o suprema da obra de Deus e o elemento mais\npr\u00f3ximo da perfei\u00e7\u00e3o (outro dos ideais que tinham que ser buscados atrav\u00e9s da\nest\u00e9tica cl\u00e1ssica). Assim, vai-se da busca de inspira\u00e7\u00e3o na natureza, \u00e0\ninspira\u00e7\u00e3o nas formas da pr\u00f3pria natureza, como os cl\u00e1ssicos prop\u00f5em,\ntornando-a um valor aut\u00f4nomo.<\/p>\n\n\n\n<p><strong>Antropocentrismo\ne humanismo:<\/strong> al\u00e9m\nda natureza como cria\u00e7\u00e3o perfeita, o olhar \u00e9 dirigido ao ser humano: o\nteocentrismo medieval \u00e9 deixado para tr\u00e1s para entrar no antropocentrismo. O\nhomem \u00e9 analisado, em vez de ser criado \u00e0 imagem e semelhan\u00e7a de Deus, como uma\nmedida e refer\u00eancia do Universo. Assim, ele ser\u00e1 o objeto central da\nmanifesta\u00e7\u00e3o art\u00edstica, com uma import\u00e2ncia ainda maior do que durante a\nantiguidade cl\u00e1ssica. O humanismo, como uma corrente filos\u00f3fica, manifestou-se\ncomo um sentimento comprometido com a representa\u00e7\u00e3o do homem no Universo,\nreafirmando assim sua presen\u00e7a. A filosofia humanista defendeu o estudo da\nnatureza como um instrumento para alcan\u00e7ar o conhecimento, mais do Universo\ncomo um todo, do que de coisas singulares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na Renascen\u00e7a americana, a ornamenta\u00e7\u00e3o renascentista \u00e9 misturada com temas inspirados na agenda decorativa dos nativos americanos. Existem dois c&#8230;<\/p>\n","protected":false},"author":1,"featured_media":596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-1486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cusco-dicas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>RENASCEN\u00c7A NA AM\u00c9RICA - Dreamy Tours<\/title>\n<meta name=\"description\" content=\"O renascimento Americano \u00e9 misturado com temas inspirados na agenda decorativa dos nativos americanos, principalmente em M\u00e9xico e Peru.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RENASCEN\u00c7A NA AM\u00c9RICA\" \/>\n<meta property=\"og:description\" content=\"O renascimento Americano \u00e9 misturado com temas inspirados na agenda decorativa dos nativos americanos, principalmente em M\u00e9xico e Peru.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/\" \/>\n<meta property=\"og:site_name\" content=\"Dreamy Tours\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dreamytours\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-03T20:44:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T23:26:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/09\/4-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dreamy Tours\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Dreamy_tours\" \/>\n<meta name=\"twitter:site\" content=\"@Dreamy_tours\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dreamy Tours\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/\"},\"author\":{\"name\":\"Dreamy Tours\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#\\\/schema\\\/person\\\/26a2534daf9eaf4cd6da8db3941552d5\"},\"headline\":\"RENASCEN\u00c7A NA AM\u00c9RICA\",\"datePublished\":\"2024-12-03T20:44:13+00:00\",\"dateModified\":\"2025-07-08T23:26:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/\"},\"wordCount\":1816,\"publisher\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/4-12.jpg\",\"articleSection\":[\"Cusco dicas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/\",\"name\":\"RENASCEN\u00c7A NA AM\u00c9RICA - Dreamy Tours\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/4-12.jpg\",\"datePublished\":\"2024-12-03T20:44:13+00:00\",\"dateModified\":\"2025-07-08T23:26:21+00:00\",\"description\":\"O renascimento Americano \u00e9 misturado com temas inspirados na agenda decorativa dos nativos americanos, principalmente em M\u00e9xico e Peru.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/4-12.jpg\",\"contentUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/4-12.jpg\",\"width\":1200,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/blog\\\/a-renascenca-na-america\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RENASCEN\u00c7A NA AM\u00c9RICA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/\",\"name\":\"Dreamy Tours\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#organization\",\"name\":\"Dreamy Tours\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/dreamy-tour-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/dreamy-tour-cuadrado.jpg\",\"width\":696,\"height\":696,\"caption\":\"Dreamy Tours\"},\"image\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dreamytours\",\"https:\\\/\\\/x.com\\\/Dreamy_tours\",\"https:\\\/\\\/www.instagram.com\\\/dreamy_tours\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/dreamy_tours\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGKP_C9x8GBYl7l8D0QD9Fg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/pt-br\\\/#\\\/schema\\\/person\\\/26a2534daf9eaf4cd6da8db3941552d5\",\"name\":\"Dreamy Tours\",\"sameAs\":[\"https:\\\/\\\/dreamy.tours\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"RENASCEN\u00c7A NA AM\u00c9RICA - Dreamy Tours","description":"O renascimento Americano \u00e9 misturado com temas inspirados na agenda decorativa dos nativos americanos, principalmente em M\u00e9xico e Peru.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/","og_locale":"pt_BR","og_type":"article","og_title":"RENASCEN\u00c7A NA AM\u00c9RICA","og_description":"O renascimento Americano \u00e9 misturado com temas inspirados na agenda decorativa dos nativos americanos, principalmente em M\u00e9xico e Peru.","og_url":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/","og_site_name":"Dreamy Tours","article_publisher":"https:\/\/www.facebook.com\/dreamytours","article_published_time":"2024-12-03T20:44:13+00:00","article_modified_time":"2025-07-08T23:26:21+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/09\/4-12.jpg","type":"image\/jpeg"}],"author":"Dreamy Tours","twitter_card":"summary_large_image","twitter_creator":"@Dreamy_tours","twitter_site":"@Dreamy_tours","twitter_misc":{"Escrito por":"Dreamy Tours","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#article","isPartOf":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/"},"author":{"name":"Dreamy Tours","@id":"https:\/\/dreamy.tours\/pt-br\/#\/schema\/person\/26a2534daf9eaf4cd6da8db3941552d5"},"headline":"RENASCEN\u00c7A NA AM\u00c9RICA","datePublished":"2024-12-03T20:44:13+00:00","dateModified":"2025-07-08T23:26:21+00:00","mainEntityOfPage":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/"},"wordCount":1816,"publisher":{"@id":"https:\/\/dreamy.tours\/pt-br\/#organization"},"image":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#primaryimage"},"thumbnailUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/09\/4-12.jpg","articleSection":["Cusco dicas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/","url":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/","name":"RENASCEN\u00c7A NA AM\u00c9RICA - Dreamy Tours","isPartOf":{"@id":"https:\/\/dreamy.tours\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#primaryimage"},"image":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#primaryimage"},"thumbnailUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/09\/4-12.jpg","datePublished":"2024-12-03T20:44:13+00:00","dateModified":"2025-07-08T23:26:21+00:00","description":"O renascimento Americano \u00e9 misturado com temas inspirados na agenda decorativa dos nativos americanos, principalmente em M\u00e9xico e Peru.","breadcrumb":{"@id":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#primaryimage","url":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/09\/4-12.jpg","contentUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/09\/4-12.jpg","width":1200,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/dreamy.tours\/pt-br\/blog\/a-renascenca-na-america\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dreamy.tours\/pt-br\/"},{"@type":"ListItem","position":2,"name":"RENASCEN\u00c7A NA AM\u00c9RICA"}]},{"@type":"WebSite","@id":"https:\/\/dreamy.tours\/pt-br\/#website","url":"https:\/\/dreamy.tours\/pt-br\/","name":"Dreamy Tours","description":"","publisher":{"@id":"https:\/\/dreamy.tours\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dreamy.tours\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/dreamy.tours\/pt-br\/#organization","name":"Dreamy Tours","url":"https:\/\/dreamy.tours\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dreamy.tours\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/dreamy.tours\/wp-content\/uploads\/dreamy-tour-cuadrado.jpg","contentUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/dreamy-tour-cuadrado.jpg","width":696,"height":696,"caption":"Dreamy Tours"},"image":{"@id":"https:\/\/dreamy.tours\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dreamytours","https:\/\/x.com\/Dreamy_tours","https:\/\/www.instagram.com\/dreamy_tours\/","https:\/\/www.pinterest.es\/dreamy_tours\/","https:\/\/www.youtube.com\/channel\/UCGKP_C9x8GBYl7l8D0QD9Fg"]},{"@type":"Person","@id":"https:\/\/dreamy.tours\/pt-br\/#\/schema\/person\/26a2534daf9eaf4cd6da8db3941552d5","name":"Dreamy Tours","sameAs":["https:\/\/dreamy.tours"]}]}},"author_meta":{"display_name":"Dreamy Tours","author_link":"https:\/\/dreamy.tours\/pt-br\/blog\/author\/admin_dt\/"},"featured_img":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/09\/4-12.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/dreamy.tours\/pt-br\/blog\/category\/cusco-dicas\/\" class=\"advgb-post-tax-term\">Cusco dicas<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Cusco dicas<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 10 meses atr\u00e1s"},"absolute_dates":{"created":"Publicado em 18 mar\u00e7o, 2024","modified":"Atualizado em 8 julho, 2025"},"absolute_dates_time":{"created":"Publicado em 18 mar\u00e7o, 2024 9:48 am","modified":"Atualizado em 8 julho, 2025 6:26 pm"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/posts\/1486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/comments?post=1486"}],"version-history":[{"count":0,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/posts\/1486\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/media\/596"}],"wp:attachment":[{"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/media?parent=1486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/categories?post=1486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dreamy.tours\/pt-br\/wp-json\/wp\/v2\/tags?post=1486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}