{"id":1436,"date":"2024-10-15T11:46:23","date_gmt":"2025-04-18T20:50:27","guid":{"rendered":"https:\/\/dreamy.tours\/?p=4222"},"modified":"2025-07-08T15:42:55","modified_gmt":"2025-07-08T20:42:55","slug":"limatambo-en-cusco","status":"publish","type":"post","link":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/","title":{"rendered":"Limatambo en Cusco"},"content":{"rendered":"\n<p>El distrito de Limatambo es uno de los 9 distritos de la provincia de Anta, ubicado en el departamento de&nbsp;<a href=\"https:\/\/dreamy.tours\/es\/ciudad-de-cusco-en-peru\/\">Cusco<\/a>, bajo la administraci\u00f3n del gobierno regional de Cuzco, en Per\u00fa.<\/p>\n\n\n\n<p>Desde el punto de vista de la jerarqu\u00eda eclesi\u00e1stica, se incluye en la Arquidi\u00f3cesis de Cusco.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/#Historia_de_Limatambo_en_Peru\" >Historia de&nbsp;Limatambo en Per\u00fa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/#Geografia_de_Limatambo_en_Cusco\" >Geograf\u00eda de&nbsp;Limatambo en Cusco<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/#Atracciones_turisticas_de_Limatambo_en_Peru\" >Atracciones tur\u00edsticas de&nbsp;Limatambo en Per\u00fa<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/#La_Luna_y_los_Petroglifos\" >La Luna y los Petroglifos<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-historia-de-limatambo-en-per\"><span class=\"ez-toc-section\" id=\"Historia_de_Limatambo_en_Peru\"><\/span>Historia de&nbsp;Limatambo en Per\u00fa<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Oficialmente, el distrito de Limatambo fue creado el 21 de junio de 1825 por decreto emitido por el Libertador Sim\u00f3n Bol\u00edvar.<\/p>\n\n\n\n<p>Durante el gobierno del alcalde Ing. Herben Rivera Alvarez, el reconocimiento por resoluci\u00f3n de la Creaci\u00f3n Pol\u00edtica del Distrito de Limatambo, Provincia de Anta, Regi\u00f3n Cusco antes de que se gestionara el Congreso de la Rep\u00fablica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-geograf-a-de-limatambo-en-cusco\"><span class=\"ez-toc-section\" id=\"Geografia_de_Limatambo_en_Cusco\"><\/span>Geograf\u00eda de&nbsp;Limatambo en Cusco<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La capital es la ciudad de&nbsp;<strong>Limatambo en Per\u00fa,<\/strong>ubicada a 2.557 metros sobre el nivel del mar. El distrito est\u00e1 bordeando el departamento de Apur\u00edmac.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-atracciones-tur-sticas-de-limatambo-en-per\"><span class=\"ez-toc-section\" id=\"Atracciones_turisticas_de_Limatambo_en_Peru\"><\/span>Atracciones tur\u00edsticas de&nbsp;Limatambo en Per\u00fa<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"647\" height=\"404\" data-id=\"2465\" src=\"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/limatambo.jpg\" alt=\"limatambo \" class=\"wp-image-2465\"\/><figcaption class=\"wp-element-caption\">limatambo &#8211; mirador de chonta<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"591\" height=\"443\" data-id=\"2468\" src=\"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/limatambo-mirador-de-chonta.jpg\" alt=\"limatambo - mirador de chonta\" class=\"wp-image-2468\"\/><figcaption class=\"wp-element-caption\">limatambo &#8211; mirador de chonta<\/figcaption><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\"><strong>Limatambo<\/strong><\/figcaption><\/figure>\n\n\n\n<p>Uno de los atractivos de este distrito son las ruinas de Tarawasi, situadas a pocos kil\u00f3metros de la ciudad del mismo nombre.<\/p>\n\n\n\n<p><strong>Limatambo en Cusco<\/strong>&nbsp;es un lugar de paso y conexi\u00f3n con la finca Mollepata, ubicada en la parte superior, punto de partida del&nbsp;<a href=\"https:\/\/dreamy.tours\/es\/cusco\/excursiones-caminatas\/cusco-y-salkantay-6-dias\/\">Salkantay Trek<\/a>&nbsp;que, despu\u00e9s de pasar por la nieve Salkantay, viaja un largo descenso que cruza la puna, las monta\u00f1as andinas, los bosques enanos y las cejas de la selva, hasta llegar a la selva alta de Santa Teresa. Una ruta menos exigente que otras ofrecidas en Cusco y que se puede hacer en campamentos o lodges. Una experiencia en la que vives una gran diversidad de suelos ecol\u00f3gicos.<\/p>\n\n\n\n<p>Mollepata es una de las muchas granjas que existen en este valle y que limita con Apur\u00edmac. En Limatambo hay otra, rodeada de vegetaci\u00f3n y con cuatro enormes palmeras en cada esquina, el Sondor, formando otra imagen \u00fanica. Lo que pasa con las palmeras es una tradici\u00f3n que viene con los terratenientes espa\u00f1oles, que a su vez lo recogieron de los \u00e1rabes, siendo una indicaci\u00f3n, en la inmensidad de las monta\u00f1as, de un lugar habitado, una especie de oasis en la carretera. La hacienda Sondor llama la atenci\u00f3n de Tarawasi debido a los colores de sus paredes y a las enormes ventanas de cristal que forman la fachada principal, provocando ligeros reflejos entre la exuberante vegetaci\u00f3n.<\/p>\n\n\n\n<p>Tarawasi es un sitio arqueol\u00f3gico raro. Un lugar inca, a tan solo 100 metros de la carretera principal, formado por terrazas, escaleras, canales de agua y paredes de piedra pulida perfectamente incrustadas entre s\u00ed con dise\u00f1os florales. Una de las paredes soporta una imponente hacienda de adobe y azulejos de dos pisos, creando una imagen algo surrealista de sincretismo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-la-luna-y-los-petroglifos\"><span class=\"ez-toc-section\" id=\"La_Luna_y_los_Petroglifos\"><\/span>La Luna y los Petroglifos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En direcci\u00f3n a Cusco, a media hora de&nbsp;<strong>Limatambo en Cusco<\/strong>&nbsp;es un lugar que creo que debe ser \u00fanico en Per\u00fa: Quillarumiyoc, el templo dedicado a Quilla, la Luna. Despu\u00e9s de escalar unos 4 kil\u00f3metros a lo largo de un camino de tierra, que comienza en Ancahuasi, a 46 kil\u00f3metros de la ciudad imperial, se llega a una explanada junto a una colina y una cueva con petroglifos en su interior, desde donde se puede ver el inmenso valle y la pampa de Anta, el granero de Cusco. En la pared m\u00e1s escondida, de espaldas a todo, una roca gigantesca tiene un semic\u00edrculo coronado por rect\u00e1ngulos grabados. El sitio tiene m\u00e1s de tres mil a\u00f1os y es un punto de encuentro para grupos m\u00edsticos que se re\u00fanen para realizar ceremonias a la Luna y la divinidad femenina, y para hacer pagos a la tierra en la cueva de los petroglifos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El distrito de Limatambo es uno de los 9 distritos de la provincia de Anta, ubicado en el departamento de&nbsp;Cusco, bajo la administraci\u00f3n del gobi&#8230;<\/p>\n","protected":false},"author":1,"featured_media":920,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-1436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tips-cusco"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Limatambo en Cusco - Tours Dreamy - America del sur<\/title>\n<meta name=\"description\" content=\"La capital es la ciudad de Limatambo en Per\u00fa, esta a 2.557 metros, El distrito est\u00e1 bordeando el departamento de Apur\u00edmac.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Limatambo en Cusco\" \/>\n<meta property=\"og:description\" content=\"La capital es la ciudad de Limatambo en Per\u00fa, esta a 2.557 metros, El distrito est\u00e1 bordeando el departamento de Apur\u00edmac.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/\" \/>\n<meta property=\"og:site_name\" content=\"Dreamy Tours\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dreamytours\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-18T20:50:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T20:42:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/4-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dreamy Tours\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Dreamy_tours\" \/>\n<meta name=\"twitter:site\" content=\"@Dreamy_tours\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dreamy Tours\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/\"},\"author\":{\"name\":\"Dreamy Tours\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/#\\\/schema\\\/person\\\/26a2534daf9eaf4cd6da8db3941552d5\"},\"headline\":\"Limatambo en Cusco\",\"datePublished\":\"2025-04-18T20:50:27+00:00\",\"dateModified\":\"2025-07-08T20:42:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/\"},\"wordCount\":648,\"publisher\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/4-7.jpg\",\"articleSection\":[\"Cusco tips\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/\",\"name\":\"Limatambo en Cusco - Tours Dreamy - America del sur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/4-7.jpg\",\"datePublished\":\"2025-04-18T20:50:27+00:00\",\"dateModified\":\"2025-07-08T20:42:55+00:00\",\"description\":\"La capital es la ciudad de Limatambo en Per\u00fa, esta a 2.557 metros, El distrito est\u00e1 bordeando el departamento de Apur\u00edmac.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/4-7.jpg\",\"contentUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/4-7.jpg\",\"width\":1200,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/blog\\\/limatambo-en-cusco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Limatambo en Cusco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/\",\"name\":\"Dreamy Tours\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/#organization\",\"name\":\"Dreamy Tours\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/dreamy-tour-cuadrado.jpg\",\"contentUrl\":\"https:\\\/\\\/dreamy.tours\\\/wp-content\\\/uploads\\\/dreamy-tour-cuadrado.jpg\",\"width\":696,\"height\":696,\"caption\":\"Dreamy Tours\"},\"image\":{\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dreamytours\",\"https:\\\/\\\/x.com\\\/Dreamy_tours\",\"https:\\\/\\\/www.instagram.com\\\/dreamy_tours\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/dreamy_tours\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGKP_C9x8GBYl7l8D0QD9Fg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dreamy.tours\\\/es\\\/#\\\/schema\\\/person\\\/26a2534daf9eaf4cd6da8db3941552d5\",\"name\":\"Dreamy Tours\",\"sameAs\":[\"https:\\\/\\\/dreamy.tours\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Limatambo en Cusco - Tours Dreamy - America del sur","description":"La capital es la ciudad de Limatambo en Per\u00fa, esta a 2.557 metros, El distrito est\u00e1 bordeando el departamento de Apur\u00edmac.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/","og_locale":"es_ES","og_type":"article","og_title":"Limatambo en Cusco","og_description":"La capital es la ciudad de Limatambo en Per\u00fa, esta a 2.557 metros, El distrito est\u00e1 bordeando el departamento de Apur\u00edmac.","og_url":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/","og_site_name":"Dreamy Tours","article_publisher":"https:\/\/www.facebook.com\/dreamytours","article_published_time":"2025-04-18T20:50:27+00:00","article_modified_time":"2025-07-08T20:42:55+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/4-7.jpg","type":"image\/jpeg"}],"author":"Dreamy Tours","twitter_card":"summary_large_image","twitter_creator":"@Dreamy_tours","twitter_site":"@Dreamy_tours","twitter_misc":{"Escrito por":"Dreamy Tours","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/#article","isPartOf":{"@id":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/"},"author":{"name":"Dreamy Tours","@id":"https:\/\/dreamy.tours\/es\/#\/schema\/person\/26a2534daf9eaf4cd6da8db3941552d5"},"headline":"Limatambo en Cusco","datePublished":"2025-04-18T20:50:27+00:00","dateModified":"2025-07-08T20:42:55+00:00","mainEntityOfPage":{"@id":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/"},"wordCount":648,"publisher":{"@id":"https:\/\/dreamy.tours\/es\/#organization"},"image":{"@id":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/#primaryimage"},"thumbnailUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/4-7.jpg","articleSection":["Cusco tips"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/","url":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/","name":"Limatambo en Cusco - Tours Dreamy - America del sur","isPartOf":{"@id":"https:\/\/dreamy.tours\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/#primaryimage"},"image":{"@id":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/#primaryimage"},"thumbnailUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/4-7.jpg","datePublished":"2025-04-18T20:50:27+00:00","dateModified":"2025-07-08T20:42:55+00:00","description":"La capital es la ciudad de Limatambo en Per\u00fa, esta a 2.557 metros, El distrito est\u00e1 bordeando el departamento de Apur\u00edmac.","breadcrumb":{"@id":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/#primaryimage","url":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/4-7.jpg","contentUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/4-7.jpg","width":1200,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/dreamy.tours\/es\/blog\/limatambo-en-cusco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dreamy.tours\/es\/"},{"@type":"ListItem","position":2,"name":"Limatambo en Cusco"}]},{"@type":"WebSite","@id":"https:\/\/dreamy.tours\/es\/#website","url":"https:\/\/dreamy.tours\/es\/","name":"Dreamy Tours","description":"","publisher":{"@id":"https:\/\/dreamy.tours\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dreamy.tours\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/dreamy.tours\/es\/#organization","name":"Dreamy Tours","url":"https:\/\/dreamy.tours\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dreamy.tours\/es\/#\/schema\/logo\/image\/","url":"https:\/\/dreamy.tours\/wp-content\/uploads\/dreamy-tour-cuadrado.jpg","contentUrl":"https:\/\/dreamy.tours\/wp-content\/uploads\/dreamy-tour-cuadrado.jpg","width":696,"height":696,"caption":"Dreamy Tours"},"image":{"@id":"https:\/\/dreamy.tours\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dreamytours","https:\/\/x.com\/Dreamy_tours","https:\/\/www.instagram.com\/dreamy_tours\/","https:\/\/www.pinterest.es\/dreamy_tours\/","https:\/\/www.youtube.com\/channel\/UCGKP_C9x8GBYl7l8D0QD9Fg"]},{"@type":"Person","@id":"https:\/\/dreamy.tours\/es\/#\/schema\/person\/26a2534daf9eaf4cd6da8db3941552d5","name":"Dreamy Tours","sameAs":["https:\/\/dreamy.tours"]}]}},"author_meta":{"display_name":"Dreamy Tours","author_link":"https:\/\/dreamy.tours\/es\/blog\/author\/admin_dt\/"},"featured_img":"https:\/\/dreamy.tours\/wp-content\/uploads\/2020\/08\/4-7.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/dreamy.tours\/es\/blog\/category\/tips-cusco\/\" class=\"advgb-post-tax-term\">Cusco tips<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Cusco tips<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 a\u00f1os hace","modified":"Actualizado 10 meses hace"},"absolute_dates":{"created":"Publicado el 15 octubre, 2024","modified":"Actualizado el 8 julio, 2025"},"absolute_dates_time":{"created":"Publicado el 15 octubre, 2024 11:46 am","modified":"Actualizado el 8 julio, 2025 3:42 pm"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/dreamy.tours\/es\/wp-json\/wp\/v2\/posts\/1436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dreamy.tours\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dreamy.tours\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dreamy.tours\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dreamy.tours\/es\/wp-json\/wp\/v2\/comments?post=1436"}],"version-history":[{"count":0,"href":"https:\/\/dreamy.tours\/es\/wp-json\/wp\/v2\/posts\/1436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dreamy.tours\/es\/wp-json\/wp\/v2\/media\/920"}],"wp:attachment":[{"href":"https:\/\/dreamy.tours\/es\/wp-json\/wp\/v2\/media?parent=1436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dreamy.tours\/es\/wp-json\/wp\/v2\/categories?post=1436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dreamy.tours\/es\/wp-json\/wp\/v2\/tags?post=1436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}